{"id":849,"date":"2019-07-09T10:32:33","date_gmt":"2019-07-09T08:32:33","guid":{"rendered":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/?p=849"},"modified":"2019-07-09T10:32:33","modified_gmt":"2019-07-09T08:32:33","slug":"maedelsflohmarkt","status":"publish","type":"post","link":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/","title":{"rendered":"Nachhaltiges Shoppen auf dem M\u00e4delsflohmarkt"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-849 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/img_1739\/'><img width=\"150\" height=\"150\" src=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1739-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-924\" srcset=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1739-150x150.jpg 150w, http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1739-810x810.jpg 810w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-924'>\n\t\t\t\tDer Raum ist gef\u00fcllt mit verkaufsfreudigen Kundinnen\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/img_1768\/'><img width=\"150\" height=\"150\" src=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1768-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-929\" srcset=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1768-150x150.jpg 150w, http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1768-810x810.jpg 810w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-929'>\n\t\t\t\tPreise k\u00f6nnen hier ausgehandelt werden\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/img_1749\/'><img width=\"150\" height=\"150\" src=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1749-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-926\" srcset=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1749-150x150.jpg 150w, http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1749-810x810.jpg 810w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-926'>\n\t\t\t\tEine Umkleide wird bereitgestellt\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/img_1756\/'><img width=\"150\" height=\"150\" src=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1756-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-928\" srcset=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1756-150x150.jpg 150w, http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1756-810x810.jpg 810w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-928'>\n\t\t\t\tAuf dem M\u00e4delsflohmarkt ist f\u00fcr jeden etwas dabei\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/img_1759\/'><img width=\"150\" height=\"150\" src=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1759-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-927\" srcset=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1759-150x150.jpg 150w, http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1759-810x810.jpg 810w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-927'>\n\t\t\t\tVerk\u00e4uferinnen bieten ihre aussortierte Kleidung an\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/img_1747\/'><img width=\"150\" height=\"150\" src=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1747-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-925\" srcset=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1747-150x150.jpg 150w, http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1747-810x810.jpg 810w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-925'>\n\t\t\t\tHier warten Schn\u00e4ppchen auf die Kundinnen\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>Die Modewelt ist eine verg\u00e4ngliche und schnelllebige Branche. Jeden Fr\u00fchling und Herbst kommen neue Trends auf den Markt und verdr\u00e4ngen die \u201ealte\u201c Kleidung aus Gesch\u00e4ften und Kleiderschr\u00e4nken. Um diesen unn\u00f6tigen Kleiderkonsum zu drosseln, muss das Tauschen und Weiterverkaufen von Kleidung zum Alltag werden. Anika hat sich deswegen auf die Suche nach einer innovativen Kleidertausch-B\u00f6rse gemacht. Der \u201eM\u00e4delsflohmarkt\u201c bietet M\u00e4dchen und Frauen in D\u00fcsseldorf, Bonn und K\u00f6ln die Chance, ihre Kleidung ein zweites Mal verwenden zu lassen und eine andere Person damit gl\u00fccklich zu machen. Mit Snacks, Getr\u00e4nken und Musik wird Second-Hand so zum Shopping-Erlebnis.<\/p>\n<p><iframe loading=\"lazy\" width=\"474\" height=\"400\" scrolling=\"no\" frameborder=\"no\" src=\"https:\/\/w.soundcloud.com\/player\/?visual=true&#038;url=https%3A%2F%2Fapi.soundcloud.com%2Ftracks%2F641808429&#038;show_artwork=true&#038;maxwidth=474&#038;maxheight=711&#038;dnt=1\"><\/iframe><\/p>\n<p>Hier findet ihr die n\u00e4chsten Termine der M\u00e4delsflohm\u00e4rkte in <a href=\"http:\/\/www.nachtkonsum.com\/maedelsflohmarkt-koeln\" target=\"_blank\" rel=\"noopener\">K\u00f6ln<\/a> und <a href=\"http:\/\/www.nachtkonsum.com\/maedelsflohmarkt-bonn\" target=\"_blank\" rel=\"noopener\">Bonn<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Modewelt ist eine verg\u00e4ngliche und schnelllebige Branche. Jeden Fr\u00fchling und Herbst kommen neue Trends auf den Markt und verdr\u00e4ngen die \u201ealte\u201c Kleidung aus Gesch\u00e4ften und Kleiderschr\u00e4nken. Um diesen unn\u00f6tigen Kleiderkonsum zu drosseln, muss das Tauschen und Weiterverkaufen von Kleidung zum Alltag werden. Anika hat sich deswegen auf die Suche nach einer innovativen Kleidertausch-B\u00f6rse gemacht. &hellip; <a href=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/\" class=\"more-link\"><span class=\"screen-reader-text\">Nachhaltiges Shoppen auf dem M\u00e4delsflohmarkt<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":167,"featured_media":930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"spay_email":""},"categories":[124],"tags":[140,141,12,139,138,142],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"Ihr seid auf der Suche nach neuer Kleidung, wollt aber nicht viel Geld ausgeben? Auf dem M\u00e4delsflohmarkt findet ihr Schn\u00e4ppchen und wirkt der Kleiderverschwendung entgegen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachhaltiges Shoppen auf dem M\u00e4delsflohmarkt\" \/>\n<meta property=\"og:description\" content=\"Ihr seid auf der Suche nach neuer Kleidung, wollt aber nicht viel Geld ausgeben? Auf dem M\u00e4delsflohmarkt findet ihr Schn\u00e4ppchen und wirkt der Kleiderverschwendung entgegen.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/\" \/>\n<meta property=\"og:site_name\" content=\"eingeVeedelt\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-09T08:32:33+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1781-1024x682.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\">\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/#website\",\"url\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/\",\"name\":\"eingeVeedelt\",\"description\":\"Journalistischer Blog \\u00fcber die Veedel von K\\u00f6ln\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1781.jpg\",\"contentUrl\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1781.jpg\",\"width\":4199,\"height\":2796,\"caption\":\"Der Andrang auf dem M\\u00e4delsflohmarkt ist gro\\u00df\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/#webpage\",\"url\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/\",\"name\":\"Nachhaltiges Shoppen auf dem M\\u00e4delsflohmarkt\",\"isPartOf\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/#primaryimage\"},\"datePublished\":\"2019-07-09T08:32:33+00:00\",\"dateModified\":\"2019-07-09T08:32:33+00:00\",\"author\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/#\/schema\/person\/fa814113eced07d82091c462c500c2c9\"},\"description\":\"Ihr seid auf der Suche nach neuer Kleidung, wollt aber nicht viel Geld ausgeben? Auf dem M\\u00e4delsflohmarkt findet ihr Schn\\u00e4ppchen und wirkt der Kleiderverschwendung entgegen.\",\"breadcrumb\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/\",\"url\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/maedelsflohmarkt\/#webpage\"}}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/#\/schema\/person\/fa814113eced07d82091c462c500c2c9\",\"name\":\"anikazuschke\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/cc233550f6119c4d4c9f1687c565cdf8?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/cc233550f6119c4d4c9f1687c565cdf8?s=96&d=mm&r=g\",\"caption\":\"anikazuschke\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","jetpack_featured_media_url":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1781.jpg","_links":{"self":[{"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/posts\/849"}],"collection":[{"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/users\/167"}],"replies":[{"embeddable":true,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/comments?post=849"}],"version-history":[{"count":5,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/posts\/849\/revisions"}],"predecessor-version":[{"id":956,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/posts\/849\/revisions\/956"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/media\/930"}],"wp:attachment":[{"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/media?parent=849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/categories?post=849"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/tags?post=849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}