{"id":853,"date":"2019-07-09T12:56:32","date_gmt":"2019-07-09T10:56:32","guid":{"rendered":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/?p=853"},"modified":"2019-07-09T12:56:32","modified_gmt":"2019-07-09T10:56:32","slug":"fitfood-statt-fastfood","status":"publish","type":"post","link":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/fitfood-statt-fastfood\/","title":{"rendered":"Fitfood statt Fastfood?"},"content":{"rendered":"<p>Die Ern\u00e4hrung spielt bei Sportlern eine sehr wichtige Rolle. Neben Training und Regeneration hat eine ausgewogene Ern\u00e4hrung den gr\u00f6\u00dften Einfluss auf die Leistung, egal ob bei Profis oder Amateuren. Bei <em>Eat For Fit<\/em> in der Bonner Stra\u00dfe finden Sportbegeisterte das, wonach sie suchen. Kai hat es ausprobiert.<\/p>\n<p><iframe loading=\"lazy\" width=\"474\" height=\"400\" scrolling=\"no\" frameborder=\"no\" src=\"https:\/\/w.soundcloud.com\/player\/?visual=true&#038;url=https%3A%2F%2Fapi.soundcloud.com%2Ftracks%2F641782551&#038;show_artwork=true&#038;maxwidth=474&#038;maxheight=711&#038;dnt=1\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Ern\u00e4hrung spielt bei Sportlern eine sehr wichtige Rolle. Neben Training und Regeneration hat eine ausgewogene Ern\u00e4hrung den gr\u00f6\u00dften Einfluss auf die Leistung, egal ob bei Profis oder Amateuren. Bei Eat For Fit in der Bonner Stra\u00dfe finden Sportbegeisterte das, wonach sie suchen. Kai hat es ausprobiert.<\/p>\n","protected":false},"author":171,"featured_media":869,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"audio","meta":{"ngg_post_thumbnail":0,"spay_email":""},"categories":[3,127],"tags":[185,82,54],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"Das Restaurant Eat For Fit in der S\u00fcdstadt ist der perfekte Ort, wenn man auf seine Ern\u00e4hrung achten will. Vor allem f\u00fcr Sportler ist das ein Muss.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/fitfood-statt-fastfood\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fitfood statt Fastfood? - eingeVeedelt\" \/>\n<meta property=\"og:description\" content=\"Das Restaurant Eat For Fit in der S\u00fcdstadt ist der perfekte Ort, wenn man auf seine Ern\u00e4hrung achten will. Vor allem f\u00fcr Sportler ist das ein Muss.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/fitfood-statt-fastfood\/\" \/>\n<meta property=\"og:site_name\" content=\"eingeVeedelt\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-09T10:56:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1732-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/#website\",\"url\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/\",\"name\":\"eingeVeedelt\",\"description\":\"Journalistischer Blog \\u00fcber die Veedel von K\\u00f6ln\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/fitfood-statt-fastfood\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1732.jpg\",\"contentUrl\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1732.jpg\",\"width\":4272,\"height\":2848},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/fitfood-statt-fastfood\/#webpage\",\"url\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/fitfood-statt-fastfood\/\",\"name\":\"Fitfood statt Fastfood? - eingeVeedelt\",\"isPartOf\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/fitfood-statt-fastfood\/#primaryimage\"},\"datePublished\":\"2019-07-09T10:56:32+00:00\",\"dateModified\":\"2019-07-09T10:56:32+00:00\",\"author\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/#\/schema\/person\/a418d48850ded08a287bba4db1914a32\"},\"description\":\"Das Restaurant Eat For Fit in der S\\u00fcdstadt ist der perfekte Ort, wenn man auf seine Ern\\u00e4hrung achten will. Vor allem f\\u00fcr Sportler ist das ein Muss.\",\"breadcrumb\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/fitfood-statt-fastfood\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/fitfood-statt-fastfood\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/fitfood-statt-fastfood\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/\",\"url\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/2019\/07\/09\/fitfood-statt-fastfood\/#webpage\"}}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/#\/schema\/person\/a418d48850ded08a287bba4db1914a32\",\"name\":\"kaifoesterling\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/e02e6e54d1b697f74d210b96f5b7a217?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/e02e6e54d1b697f74d210b96f5b7a217?s=96&d=mm&r=g\",\"caption\":\"kaifoesterling\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","jetpack_featured_media_url":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-content\/uploads\/sites\/139\/2019\/06\/IMG_1732.jpg","_links":{"self":[{"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/posts\/853"}],"collection":[{"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/users\/171"}],"replies":[{"embeddable":true,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/comments?post=853"}],"version-history":[{"count":5,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/posts\/853\/revisions"}],"predecessor-version":[{"id":1231,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/posts\/853\/revisions\/1231"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/media\/869"}],"wp:attachment":[{"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/media?parent=853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/categories?post=853"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/tags?post=853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}