{"id":108,"count":1,"description":"","link":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/tag\/koeski-royal\/","name":"K\u00f6ski Royal","slug":"koeski-royal","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/tag\/koeski-royal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"K\u00f6ski Royal Archive - eingeVeedelt\" \/>\n<meta property=\"og:url\" content=\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/tag\/koeski-royal\/\" \/>\n<meta property=\"og:site_name\" content=\"eingeVeedelt\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/#website\",\"url\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/\",\"name\":\"eingeVeedelt\",\"description\":\"Journalistischer Blog \\u00fcber die Veedel von K\\u00f6ln\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/tag\/koeski-royal\/#webpage\",\"url\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/tag\/koeski-royal\/\",\"name\":\"K\\u00f6ski Royal Archive - eingeVeedelt\",\"isPartOf\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/tag\/koeski-royal\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/tag\/koeski-royal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/tag\/koeski-royal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/\",\"url\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/tag\/koeski-royal\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/tags\/108"}],"collection":[{"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/journalcologne.hmkw.de\/eingeveedelt\/wp-json\/wp\/v2\/posts?tags=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}